{"id":2993,"date":"2022-07-18T12:00:35","date_gmt":"2022-07-18T10:00:35","guid":{"rendered":"https:\/\/parqueminerodealmaden.es\/?p=2993"},"modified":"2023-03-06T09:33:45","modified_gmt":"2023-03-06T08:33:45","slug":"en-la-mina-banda-municipal-de-almaden-isaac-perello-marti-minas-de-almaden-10o-aniversario","status":"publish","type":"post","link":"https:\/\/parqueminerodealmaden.es\/en\/en-la-mina-banda-municipal-de-almaden-isaac-perello-marti-minas-de-almaden-10o-aniversario\/","title":{"rendered":"EN LA MINA. Banda Municipal de Almad\u00e9n. Isaac Perell\u00f3 Mart\u00ed. Minas de Almad\u00e9n. 10\u00ba Aniversario."},"content":{"rendered":"\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"EN LA MINA. Banda Municipal de Almad\u00e9n. Isaac Perell\u00f3 Mart\u00ed. Minas de Almad\u00e9n. 10\u00ba Aniversario.\" width=\"720\" height=\"405\" data-src=\"https:\/\/www.youtube.com\/embed\/WJX_WZ9vW4E?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" data-load-mode=\"0\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Como parte de las actividades ideadas e impulsadas por Minas de Almad\u00e9n Parque Minero con motivo del 10\u00ba aniversario de la declaraci\u00f3n de Patrimonio de la Humanidad, Patrimonio de Mercurio Almad\u00e9n Idrija, 2012-2022. D. Isaac Perell\u00f3 Mart\u00ed, director de la Asociaci\u00f3n Musical &#8220;Banda Municipal de Almad\u00e9n&#8221;, a propuesta de Minas de Almad\u00e9n ha compuesto una pieza conmemorativa inspirada en la historia de las Minas de Almad\u00e9n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">EN LA MINA. &#8220;Preludio sinf\u00f3nico para la celebraci\u00f3n del X Aniversario de la declaraci\u00f3n del Patrimonio del Mercurio Almad\u00e9n e Idria. Se trata de una peque\u00f1a pieza para vientos y percusi\u00f3n dividida en seis partes, diferenciadas por la instrumentaci\u00f3n m\u00e1s representativa encada parte, pasando por todas las familias instrumentales de la banda sinf\u00f3nica, percusi\u00f3n, madera aguda, grupo de clarinetes, metales,<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">grupo de saxos y formaci\u00f3n completa. Tiene un car\u00e1cter \u00e9pico y emocional, como el trabajo de los mineros en las minas de mercurio de Almad\u00e9n, percusivo y repetitivo. Las seis partes de la obra tambi\u00e9n evocan y representan los hex\u00e1gonos que se pueden observar en varias edificaciones del Patrimonio como son las Hexagonal plaza de toros hist\u00f3rica de Almad\u00e9n o el fabuloso Baritel del interior de la mina&#8221;. Isaac Perell\u00f3 Mart\u00ed.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El proyecto tiene como principal objetivo el de consolidar a Mayasa y Minas de Almad\u00e9n Parque Minero como promotor de la creaci\u00f3n y producci\u00f3n de nuevos contenidos culturales, a partir, tanto de la propia fuerza creativa de los habitantes del territorio, como reconociendo y respaldando a creadores externos en proyectos sensibles con nuestra realidad cultural, art\u00edstica y vital. La historia de las Minas de Almad\u00e9n y su entorno natural, cultural y social suponen una fuente de inspiraci\u00f3n extraordinaria en la que sobresalen los valores de una realidad natural, hist\u00f3rica, econ\u00f3mica, antropol\u00f3gica, industrial, minera y cient\u00edfica de gran complejidad y transcendencia para Espa\u00f1a y el mundo, es por ello que ha sido reconocida como Patrimonio de la Humanidad, Sello Europeo de Patrimonio y Sitio Europeo de la Qu\u00edmica. Esta fant\u00e1stica iniciativa simboliza en el 10\u00ba aniversario de la declaraci\u00f3n de Patrimonio de la Humanidad. Patrimonio del Mercurio Almad\u00e9n e Idrija. la trascendencia de estos valores para mantener vivo el sentido del lugar y cumplir con nuestra misi\u00f3n de cuidar y divulgar el patrimonio del todos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde Minas de Almad\u00e9n Parque Minero, quedemos agradecer la extraordinaria labor del compositor y director de la pieza, as\u00ed como a todos y cada uno de los m\u00fasicos que componen la Asociaci\u00f3n Musical &#8220;Banda Municipal de Almad\u00e9n&#8221; por su esfuerzo y dedicaci\u00f3n, y por compartir su talento en este proyecto y con todos nosotros.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Como parte de las actividades ideadas e impulsadas por Minas de Almad\u00e9n Parque Minero con motivo del 10\u00ba aniversario de la declaraci\u00f3n de Patrimonio de&#8230;<\/p>\n","protected":false},"author":1,"featured_media":2497,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[39],"tags":[],"class_list":["post-2993","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-en"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u25b7 EN LA MINA. Banda Municipal de Almad\u00e9n. Isaac Perell\u00f3 Mart\u00ed. Minas de Almad\u00e9n. 10\u00ba Aniversario. - Parque Minero de Almad\u00e9n<\/title>\n<meta name=\"description\" content=\"Descubre el Parque Minero de Almad\u00e9n, Patrimonio de la Humanidad, y vive una experiencia \u00fanica explorando las antiguas minas de mercurio.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/parqueminerodealmaden.es\/en\/en-la-mina-banda-municipal-de-almaden-isaac-perello-marti-minas-de-almaden-10o-aniversario\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u25b7 EN LA MINA. Banda Municipal de Almad\u00e9n. Isaac Perell\u00f3 Mart\u00ed. Minas de Almad\u00e9n. 10\u00ba Aniversario. - Parque Minero de Almad\u00e9n\" \/>\n<meta property=\"og:description\" content=\"Descubre el Parque Minero de Almad\u00e9n, Patrimonio de la Humanidad, y vive una experiencia \u00fanica explorando las antiguas minas de mercurio.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/parqueminerodealmaden.es\/en\/en-la-mina-banda-municipal-de-almaden-isaac-perello-marti-minas-de-almaden-10o-aniversario\/\" \/>\n<meta property=\"og:site_name\" content=\"Parque Minero de Almad\u00e9n\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-18T10:00:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-06T08:33:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/parqueminerodealmaden.es\/wp-content\/uploads\/2022\/07\/banda-municipal-almaden.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"expacioweb\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"expacioweb\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/parqueminerodealmaden.es\\\/en\\\/en-la-mina-banda-municipal-de-almaden-isaac-perello-marti-minas-de-almaden-10o-aniversario\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/parqueminerodealmaden.es\\\/en\\\/en-la-mina-banda-municipal-de-almaden-isaac-perello-marti-minas-de-almaden-10o-aniversario\\\/\"},\"author\":{\"name\":\"expacioweb\",\"@id\":\"https:\\\/\\\/parqueminerodealmaden.es\\\/en\\\/#\\\/schema\\\/person\\\/5a013ea1e7fcf3225c683db598e17253\"},\"headline\":\"EN LA MINA. Banda Municipal de Almad\u00e9n. Isaac Perell\u00f3 Mart\u00ed. Minas de Almad\u00e9n. 10\u00ba Aniversario.\",\"datePublished\":\"2022-07-18T10:00:35+00:00\",\"dateModified\":\"2023-03-06T08:33:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/parqueminerodealmaden.es\\\/en\\\/en-la-mina-banda-municipal-de-almaden-isaac-perello-marti-minas-de-almaden-10o-aniversario\\\/\"},\"wordCount\":491,\"publisher\":{\"@id\":\"https:\\\/\\\/parqueminerodealmaden.es\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/parqueminerodealmaden.es\\\/en\\\/en-la-mina-banda-municipal-de-almaden-isaac-perello-marti-minas-de-almaden-10o-aniversario\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/parqueminerodealmaden.es\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/banda-municipal-almaden.jpg\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/parqueminerodealmaden.es\\\/en\\\/en-la-mina-banda-municipal-de-almaden-isaac-perello-marti-minas-de-almaden-10o-aniversario\\\/\",\"url\":\"https:\\\/\\\/parqueminerodealmaden.es\\\/en\\\/en-la-mina-banda-municipal-de-almaden-isaac-perello-marti-minas-de-almaden-10o-aniversario\\\/\",\"name\":\"\u25b7 EN LA MINA. Banda Municipal de Almad\u00e9n. Isaac Perell\u00f3 Mart\u00ed. Minas de Almad\u00e9n. 10\u00ba Aniversario. - Parque Minero de Almad\u00e9n\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/parqueminerodealmaden.es\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/parqueminerodealmaden.es\\\/en\\\/en-la-mina-banda-municipal-de-almaden-isaac-perello-marti-minas-de-almaden-10o-aniversario\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/parqueminerodealmaden.es\\\/en\\\/en-la-mina-banda-municipal-de-almaden-isaac-perello-marti-minas-de-almaden-10o-aniversario\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/parqueminerodealmaden.es\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/banda-municipal-almaden.jpg\",\"datePublished\":\"2022-07-18T10:00:35+00:00\",\"dateModified\":\"2023-03-06T08:33:45+00:00\",\"description\":\"Descubre el Parque Minero de Almad\u00e9n, Patrimonio de la Humanidad, y vive una experiencia \u00fanica explorando las antiguas minas de mercurio.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/parqueminerodealmaden.es\\\/en\\\/en-la-mina-banda-municipal-de-almaden-isaac-perello-marti-minas-de-almaden-10o-aniversario\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/parqueminerodealmaden.es\\\/en\\\/en-la-mina-banda-municipal-de-almaden-isaac-perello-marti-minas-de-almaden-10o-aniversario\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/parqueminerodealmaden.es\\\/en\\\/en-la-mina-banda-municipal-de-almaden-isaac-perello-marti-minas-de-almaden-10o-aniversario\\\/#primaryimage\",\"url\":\"https:\\\/\\\/parqueminerodealmaden.es\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/banda-municipal-almaden.jpg\",\"contentUrl\":\"https:\\\/\\\/parqueminerodealmaden.es\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/banda-municipal-almaden.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"Banda municipal de Almad\u00e9n\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/parqueminerodealmaden.es\\\/en\\\/en-la-mina-banda-municipal-de-almaden-isaac-perello-marti-minas-de-almaden-10o-aniversario\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/parqueminerodealmaden.es\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EN LA MINA. Banda Municipal de Almad\u00e9n. Isaac Perell\u00f3 Mart\u00ed. Minas de Almad\u00e9n. 10\u00ba Aniversario.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/parqueminerodealmaden.es\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/parqueminerodealmaden.es\\\/en\\\/\",\"name\":\"Parque Minero de Almad\u00e9n\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/parqueminerodealmaden.es\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/parqueminerodealmaden.es\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/parqueminerodealmaden.es\\\/en\\\/#organization\",\"name\":\"Parque Minero de Almad\u00e9n\",\"url\":\"https:\\\/\\\/parqueminerodealmaden.es\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/parqueminerodealmaden.es\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/parqueminerodealmaden.es\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/parque-minero-de-almaden.svg\",\"contentUrl\":\"https:\\\/\\\/parqueminerodealmaden.es\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/parque-minero-de-almaden.svg\",\"width\":135,\"height\":116,\"caption\":\"Parque Minero de Almad\u00e9n\"},\"image\":{\"@id\":\"https:\\\/\\\/parqueminerodealmaden.es\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/parqueminerodealmaden.es\\\/en\\\/#\\\/schema\\\/person\\\/5a013ea1e7fcf3225c683db598e17253\",\"name\":\"expacioweb\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/07b32851c062aa81cbe52c771bc99557421783ed894593d330426537edebbff5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/07b32851c062aa81cbe52c771bc99557421783ed894593d330426537edebbff5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/07b32851c062aa81cbe52c771bc99557421783ed894593d330426537edebbff5?s=96&d=mm&r=g\",\"caption\":\"expacioweb\"},\"sameAs\":[\"https:\\\/\\\/parqueminerodealmaden.es\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u25b7 EN LA MINA. Banda Municipal de Almad\u00e9n. Isaac Perell\u00f3 Mart\u00ed. Minas de Almad\u00e9n. 10\u00ba Aniversario. - Parque Minero de Almad\u00e9n","description":"Descubre el Parque Minero de Almad\u00e9n, Patrimonio de la Humanidad, y vive una experiencia \u00fanica explorando las antiguas minas de mercurio.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/parqueminerodealmaden.es\/en\/en-la-mina-banda-municipal-de-almaden-isaac-perello-marti-minas-de-almaden-10o-aniversario\/","og_locale":"en_US","og_type":"article","og_title":"\u25b7 EN LA MINA. Banda Municipal de Almad\u00e9n. Isaac Perell\u00f3 Mart\u00ed. Minas de Almad\u00e9n. 10\u00ba Aniversario. - Parque Minero de Almad\u00e9n","og_description":"Descubre el Parque Minero de Almad\u00e9n, Patrimonio de la Humanidad, y vive una experiencia \u00fanica explorando las antiguas minas de mercurio.","og_url":"https:\/\/parqueminerodealmaden.es\/en\/en-la-mina-banda-municipal-de-almaden-isaac-perello-marti-minas-de-almaden-10o-aniversario\/","og_site_name":"Parque Minero de Almad\u00e9n","article_published_time":"2022-07-18T10:00:35+00:00","article_modified_time":"2023-03-06T08:33:45+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/parqueminerodealmaden.es\/wp-content\/uploads\/2022\/07\/banda-municipal-almaden.jpg","type":"image\/jpeg"}],"author":"expacioweb","twitter_card":"summary_large_image","twitter_misc":{"Written by":"expacioweb","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/parqueminerodealmaden.es\/en\/en-la-mina-banda-municipal-de-almaden-isaac-perello-marti-minas-de-almaden-10o-aniversario\/#article","isPartOf":{"@id":"https:\/\/parqueminerodealmaden.es\/en\/en-la-mina-banda-municipal-de-almaden-isaac-perello-marti-minas-de-almaden-10o-aniversario\/"},"author":{"name":"expacioweb","@id":"https:\/\/parqueminerodealmaden.es\/en\/#\/schema\/person\/5a013ea1e7fcf3225c683db598e17253"},"headline":"EN LA MINA. Banda Municipal de Almad\u00e9n. Isaac Perell\u00f3 Mart\u00ed. Minas de Almad\u00e9n. 10\u00ba Aniversario.","datePublished":"2022-07-18T10:00:35+00:00","dateModified":"2023-03-06T08:33:45+00:00","mainEntityOfPage":{"@id":"https:\/\/parqueminerodealmaden.es\/en\/en-la-mina-banda-municipal-de-almaden-isaac-perello-marti-minas-de-almaden-10o-aniversario\/"},"wordCount":491,"publisher":{"@id":"https:\/\/parqueminerodealmaden.es\/en\/#organization"},"image":{"@id":"https:\/\/parqueminerodealmaden.es\/en\/en-la-mina-banda-municipal-de-almaden-isaac-perello-marti-minas-de-almaden-10o-aniversario\/#primaryimage"},"thumbnailUrl":"https:\/\/parqueminerodealmaden.es\/wp-content\/uploads\/2022\/07\/banda-municipal-almaden.jpg","articleSection":["Blog"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/parqueminerodealmaden.es\/en\/en-la-mina-banda-municipal-de-almaden-isaac-perello-marti-minas-de-almaden-10o-aniversario\/","url":"https:\/\/parqueminerodealmaden.es\/en\/en-la-mina-banda-municipal-de-almaden-isaac-perello-marti-minas-de-almaden-10o-aniversario\/","name":"\u25b7 EN LA MINA. Banda Municipal de Almad\u00e9n. Isaac Perell\u00f3 Mart\u00ed. Minas de Almad\u00e9n. 10\u00ba Aniversario. - Parque Minero de Almad\u00e9n","isPartOf":{"@id":"https:\/\/parqueminerodealmaden.es\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/parqueminerodealmaden.es\/en\/en-la-mina-banda-municipal-de-almaden-isaac-perello-marti-minas-de-almaden-10o-aniversario\/#primaryimage"},"image":{"@id":"https:\/\/parqueminerodealmaden.es\/en\/en-la-mina-banda-municipal-de-almaden-isaac-perello-marti-minas-de-almaden-10o-aniversario\/#primaryimage"},"thumbnailUrl":"https:\/\/parqueminerodealmaden.es\/wp-content\/uploads\/2022\/07\/banda-municipal-almaden.jpg","datePublished":"2022-07-18T10:00:35+00:00","dateModified":"2023-03-06T08:33:45+00:00","description":"Descubre el Parque Minero de Almad\u00e9n, Patrimonio de la Humanidad, y vive una experiencia \u00fanica explorando las antiguas minas de mercurio.","breadcrumb":{"@id":"https:\/\/parqueminerodealmaden.es\/en\/en-la-mina-banda-municipal-de-almaden-isaac-perello-marti-minas-de-almaden-10o-aniversario\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/parqueminerodealmaden.es\/en\/en-la-mina-banda-municipal-de-almaden-isaac-perello-marti-minas-de-almaden-10o-aniversario\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/parqueminerodealmaden.es\/en\/en-la-mina-banda-municipal-de-almaden-isaac-perello-marti-minas-de-almaden-10o-aniversario\/#primaryimage","url":"https:\/\/parqueminerodealmaden.es\/wp-content\/uploads\/2022\/07\/banda-municipal-almaden.jpg","contentUrl":"https:\/\/parqueminerodealmaden.es\/wp-content\/uploads\/2022\/07\/banda-municipal-almaden.jpg","width":1920,"height":1080,"caption":"Banda municipal de Almad\u00e9n"},{"@type":"BreadcrumbList","@id":"https:\/\/parqueminerodealmaden.es\/en\/en-la-mina-banda-municipal-de-almaden-isaac-perello-marti-minas-de-almaden-10o-aniversario\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/parqueminerodealmaden.es\/en\/"},{"@type":"ListItem","position":2,"name":"EN LA MINA. Banda Municipal de Almad\u00e9n. Isaac Perell\u00f3 Mart\u00ed. Minas de Almad\u00e9n. 10\u00ba Aniversario."}]},{"@type":"WebSite","@id":"https:\/\/parqueminerodealmaden.es\/en\/#website","url":"https:\/\/parqueminerodealmaden.es\/en\/","name":"Parque Minero de Almad\u00e9n","description":"","publisher":{"@id":"https:\/\/parqueminerodealmaden.es\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/parqueminerodealmaden.es\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/parqueminerodealmaden.es\/en\/#organization","name":"Parque Minero de Almad\u00e9n","url":"https:\/\/parqueminerodealmaden.es\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/parqueminerodealmaden.es\/en\/#\/schema\/logo\/image\/","url":"https:\/\/parqueminerodealmaden.es\/wp-content\/uploads\/2021\/12\/parque-minero-de-almaden.svg","contentUrl":"https:\/\/parqueminerodealmaden.es\/wp-content\/uploads\/2021\/12\/parque-minero-de-almaden.svg","width":135,"height":116,"caption":"Parque Minero de Almad\u00e9n"},"image":{"@id":"https:\/\/parqueminerodealmaden.es\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/parqueminerodealmaden.es\/en\/#\/schema\/person\/5a013ea1e7fcf3225c683db598e17253","name":"expacioweb","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/07b32851c062aa81cbe52c771bc99557421783ed894593d330426537edebbff5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/07b32851c062aa81cbe52c771bc99557421783ed894593d330426537edebbff5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/07b32851c062aa81cbe52c771bc99557421783ed894593d330426537edebbff5?s=96&d=mm&r=g","caption":"expacioweb"},"sameAs":["https:\/\/parqueminerodealmaden.es"]}]}},"taxonomy_info":{"category":[{"value":39,"label":"Blog"}]},"featured_image_src_large":["https:\/\/parqueminerodealmaden.es\/wp-content\/uploads\/2022\/07\/banda-municipal-almaden-1024x576.jpg",1024,576,true],"author_info":{"display_name":"expacioweb","author_link":"https:\/\/parqueminerodealmaden.es\/en\/author\/expacioweb\/"},"comment_info":0,"category_info":[{"term_id":39,"name":"Blog","slug":"blog-en","term_group":0,"term_taxonomy_id":39,"taxonomy":"category","description":"","parent":0,"count":23,"filter":"raw","cat_ID":39,"category_count":23,"category_description":"","cat_name":"Blog","category_nicename":"blog-en","category_parent":0}],"tag_info":false,"_links":{"self":[{"href":"https:\/\/parqueminerodealmaden.es\/en\/wp-json\/wp\/v2\/posts\/2993","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/parqueminerodealmaden.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/parqueminerodealmaden.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/parqueminerodealmaden.es\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/parqueminerodealmaden.es\/en\/wp-json\/wp\/v2\/comments?post=2993"}],"version-history":[{"count":1,"href":"https:\/\/parqueminerodealmaden.es\/en\/wp-json\/wp\/v2\/posts\/2993\/revisions"}],"predecessor-version":[{"id":2994,"href":"https:\/\/parqueminerodealmaden.es\/en\/wp-json\/wp\/v2\/posts\/2993\/revisions\/2994"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/parqueminerodealmaden.es\/en\/wp-json\/wp\/v2\/media\/2497"}],"wp:attachment":[{"href":"https:\/\/parqueminerodealmaden.es\/en\/wp-json\/wp\/v2\/media?parent=2993"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/parqueminerodealmaden.es\/en\/wp-json\/wp\/v2\/categories?post=2993"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/parqueminerodealmaden.es\/en\/wp-json\/wp\/v2\/tags?post=2993"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}